{"id":243,"count":0,"description":"","link":"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/","name":"Assistant de s\u00e9lection des scies \u00e0 ruban","slug":"assistant-de-selection-des-scies-a-ruban","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Assistant de s\u00e9lection des scies \u00e0 ruban - sklep internetowy - Koronet<\/title>\n<meta name=\"description\" content=\"Assistant de s\u00e9lection des scies \u00e0 ruban- Niezale\u017cnie od rodzaju obrabianych materia\u0142\u00f3w, b\u0119dziemy w stanie dostarczy\u0107 do Twojej firmy ta\u015bmy tn\u0105ce o najwy\u017cszych parametrach jako\u015bciowych \u2705.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assistant de s\u00e9lection des scies \u00e0 ruban - sklep internetowy - Koronet\" \/>\n<meta property=\"og:description\" content=\"Assistant de s\u00e9lection des scies \u00e0 ruban- Niezale\u017cnie od rodzaju obrabianych materia\u0142\u00f3w, b\u0119dziemy w stanie dostarczy\u0107 do Twojej firmy ta\u015bmy tn\u0105ce o najwy\u017cszych parametrach jako\u015bciowych \u2705.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/\" \/>\n<meta property=\"og:site_name\" content=\"Koronet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/produkty\\\/assistant-de-selection-des-scies-a-ruban\\\/\",\"url\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/produkty\\\/assistant-de-selection-des-scies-a-ruban\\\/\",\"name\":\"Assistant de s\u00e9lection des scies \u00e0 ruban - sklep internetowy - Koronet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/#website\"},\"description\":\"Assistant de s\u00e9lection des scies \u00e0 ruban- Niezale\u017cnie od rodzaju obrabianych materia\u0142\u00f3w, b\u0119dziemy w stanie dostarczy\u0107 do Twojej firmy ta\u015bmy tn\u0105ce o najwy\u017cszych parametrach jako\u015bciowych \u2705.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/produkty\\\/assistant-de-selection-des-scies-a-ruban\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/produkty\\\/assistant-de-selection-des-scies-a-ruban\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Assistant de s\u00e9lection des scies \u00e0 ruban\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/\",\"name\":\"Koronet\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/#organization\",\"name\":\"Koronet\",\"alternateName\":\"Koronet\",\"url\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.koro.net.pl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Koronet-spolka-z-o.o.png\",\"contentUrl\":\"https:\\\/\\\/www.koro.net.pl\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Koronet-spolka-z-o.o.png\",\"width\":696,\"height\":696,\"caption\":\"Koronet\"},\"image\":{\"@id\":\"https:\\\/\\\/www.koro.net.pl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Assistant de s\u00e9lection des scies \u00e0 ruban - sklep internetowy - Koronet","description":"Assistant de s\u00e9lection des scies \u00e0 ruban- Niezale\u017cnie od rodzaju obrabianych materia\u0142\u00f3w, b\u0119dziemy w stanie dostarczy\u0107 do Twojej firmy ta\u015bmy tn\u0105ce o najwy\u017cszych parametrach jako\u015bciowych \u2705.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/","og_locale":"fr_FR","og_type":"article","og_title":"Assistant de s\u00e9lection des scies \u00e0 ruban - sklep internetowy - Koronet","og_description":"Assistant de s\u00e9lection des scies \u00e0 ruban- Niezale\u017cnie od rodzaju obrabianych materia\u0142\u00f3w, b\u0119dziemy w stanie dostarczy\u0107 do Twojej firmy ta\u015bmy tn\u0105ce o najwy\u017cszych parametrach jako\u015bciowych \u2705.","og_url":"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/","og_site_name":"Koronet","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/","url":"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/","name":"Assistant de s\u00e9lection des scies \u00e0 ruban - sklep internetowy - Koronet","isPartOf":{"@id":"https:\/\/www.koro.net.pl\/fr\/#website"},"description":"Assistant de s\u00e9lection des scies \u00e0 ruban- Niezale\u017cnie od rodzaju obrabianych materia\u0142\u00f3w, b\u0119dziemy w stanie dostarczy\u0107 do Twojej firmy ta\u015bmy tn\u0105ce o najwy\u017cszych parametrach jako\u015bciowych \u2705.","breadcrumb":{"@id":"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.koro.net.pl\/fr\/produkty\/assistant-de-selection-des-scies-a-ruban\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/www.koro.net.pl\/fr\/"},{"@type":"ListItem","position":2,"name":"Assistant de s\u00e9lection des scies \u00e0 ruban"}]},{"@type":"WebSite","@id":"https:\/\/www.koro.net.pl\/fr\/#website","url":"https:\/\/www.koro.net.pl\/fr\/","name":"Koronet","description":"","publisher":{"@id":"https:\/\/www.koro.net.pl\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.koro.net.pl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.koro.net.pl\/fr\/#organization","name":"Koronet","alternateName":"Koronet","url":"https:\/\/www.koro.net.pl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.koro.net.pl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.koro.net.pl\/wp-content\/uploads\/2025\/02\/Koronet-spolka-z-o.o.png","contentUrl":"https:\/\/www.koro.net.pl\/wp-content\/uploads\/2025\/02\/Koronet-spolka-z-o.o.png","width":696,"height":696,"caption":"Koronet"},"image":{"@id":"https:\/\/www.koro.net.pl\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.koro.net.pl\/fr\/wp-json\/wp\/v2\/product_cat\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.koro.net.pl\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.koro.net.pl\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.koro.net.pl\/fr\/wp-json\/wp\/v2\/product?product_cat=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}